{"id":3151,"date":"2023-11-29T14:24:24","date_gmt":"2023-11-29T13:24:24","guid":{"rendered":"https:\/\/cineclubbedarieux.fr\/?p=3151"},"modified":"2025-08-25T11:21:54","modified_gmt":"2025-08-25T09:21:54","slug":"les-filles-dolfa-lundi-8-janvier-20h30","status":"publish","type":"post","link":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/","title":{"rendered":"\u00ab\u00a0Les filles d&rsquo;Olfa\u00a0\u00bb lundi 8 janvier 20h30"},"content":{"rendered":"\n<p><strong>Tunisie, (2023), un film de Kaouther Ben Hania. 1h50 avec Hend Sabri, Olfa Hamrouni, Eya Chikahoui<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color\"><strong>Olfa,  m\u00e8re de 4 filles, un jour, ses deux filles a\u00een\u00e9es disparaissent. Pour combler leur absence, la r\u00e9alisatrice Kaouther Ben Hania convoque des actrices professionnelles et met en place un dispositif de cin\u00e9ma hors du commun afin de lever le voile sur l\u2019histoire d\u2019Olfa et ses filles<\/strong>. <\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color\"><strong>Un voyage intime fait d\u2019espoir, de r\u00e9bellion, de violence, de transmission et de sororit\u00e9 <\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"348\" height=\"145\" src=\"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa.jpg\" alt=\"\" class=\"wp-image-3171\" style=\"width:594px;height:248px\" srcset=\"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa.jpg 348w, https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa-300x125.jpg 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-drop-cap has-vivid-cyan-blue-color has-text-color\"><strong>Les Filles d\u2019Olfa est donc un film qui raconte le film en train de se faire : une fiction o\u00f9 les deux filles absentes sont incarn\u00e9es par des actrices, Olfa elle-m\u00eame ayant une \u00ab doublure \u00bb pour les sc\u00e8nes \u00e9motionnellement trop difficiles \u2013 les deux s\u0153urs cadettes d\u00e9sormais proches de l\u2019\u00e2ge adulte jouant leur propre r\u00f4le. Tout en bienveillance et en pudeur, la r\u00e9alisatrice guide \u00e0 peine les \u00e9changes, laisse les trois femmes raconter les sc\u00e8nes, se compl\u00e9ter, parfois se contredire sur un d\u00e9tail \u2013 et diriger elles-m\u00eames les com\u00e9diennes qui incarnent les s\u0153urs et la m\u00e8re. Ce pourrait \u00eatre aust\u00e8re, froid, th\u00e9orique, conceptuel, pr\u00e9tentieux, bref : somptueusement emmerdant\u2026 or, non ! C\u2019est beau, c\u2019est frais, c\u2019est juste \u2013 c\u2019est m\u00eame joyeux \u2013 et subtilement \u00e9mouvant. Une fois n\u2019est pas coutume, une v\u00e9ritable \u00ab magie du cin\u00e9ma \u00bb (la fameuse !) op\u00e8re, et le dispositif, pourtant plus que visible, s\u2019oublie instantan\u00e9ment, se fond harmonieusement dans cette histoire superbe, poignante, qui reprend vie sous nos yeux embu\u00e9s. Sans une once de voyeurisme, l\u2019\u00e9motion, parfois jou\u00e9e, parfois simplement capt\u00e9e, affleure \u00e0 chaque instant, passant du drame au tragi-comique dans des encha\u00eenements que de toute \u00e9vidence seule la vie sait sc\u00e9nariser.<\/strong> Utopia<\/p>\n\n\n\n<p class=\"has-drop-cap has-vivid-cyan-blue-color has-text-color\"><strong>la r\u00e9alisatrice trouve dans ce projet filmique une mati\u00e8re \u00e0 r\u00e9flexion particuli\u00e8rement riche pour prolonger son traitement des probl\u00e9matiques culturelles et sociales inh\u00e9rentes au monde arabe. Plus qu\u2019un portrait de famille, Les filles d\u2019Olfa fait se confronter deux g\u00e9n\u00e9rations de femmes : d\u2019un c\u00f4t\u00e9 Olfa, qui malgr\u00e9 une volont\u00e9 de fer n\u2019a jamais vraiment r\u00e9ussi \u00e0 s\u2019\u00e9manciper du mod\u00e8le de violence patriarcale intrins\u00e8que \u00e0 son environnement ; de l\u2019autre Eya et Tayssir, ses filles cadettes bien d\u00e9termin\u00e9es \u00e0 rester ma\u00eetresses de leurs destins et de leurs corps. Leurs \u00e9changes assertifs ainsi que le monologue final d\u2019Olfa sur comment \u2018\u2019briser la chaine de la violence\u2019\u2019 donnent au film une force politique particuli\u00e8rement pertinente. <\/strong>le Bleu du miroir<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>La r\u00e9alisatrice<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color\"><em>Kaouther Ben Hania fait ses \u00e9tudes en cin\u00e9ma \u00e0 Tunis et \u00e0 Paris (la F\u00e9mis et la Sorbonne).<br>Elle r\u00e9alise plusieurs courts-m\u00e9trages. Le Challat de Tunis, son premier long-m\u00e9trage, ouvre la section ACID du Festival de Cannes en 2014 et connait un succ\u00e8s international aussi bien en festivals, qu\u2019en salles, o\u00f9 il sera distribu\u00e9 dans plus de 15 pays.<br>Elle signe ensuite Zaineb n\u2019aime pas la neige, long-m\u00e9\u0002trage documentaire tourn\u00e9 durant 6 ans entre la Tuni\u0002sie et le Canada. Son film de fiction La Belle et la Meute est s\u00e9lectionn\u00e9 au Festival de Cannes 2017 dans la section Un Certain Regard .<br>Son film suivant L\u2019homme qui a vendu sa peau, avec Monica Bellucci, a \u00e9t\u00e9 pr\u00e9sent\u00e9 en s\u00e9lection officielle \u00e0 la Mostra de Venise et a \u00e9t\u00e9 nomin\u00e9 aux Oscars pour le Meilleur Film \u00c9tranger 2021.<br>Kaouther Ben Hania, qui exp\u00e9rimente constamment son travail documentaire et de fiction, concourt pour la premi\u00e8re fois en Comp\u00e9tition Officielle au Festival de Cannes 2023 avec Les Filles d\u2019Olfa<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>Son interview<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color\"><strong>L\u2019histoire d\u2019Olfa est-elle connue en Tunisie ?<\/strong><\/p>\n\n\n\n<p class=\"has-vivid-purple-color has-text-color\">\u2014 Disons qu\u2019au moment o\u00f9 je la contacte, elle est pass\u00e9e de nombreuses fois \u00e0 la radio et \u00e0 la t\u00e9l\u00e9vision. Mais il faut<br>comprendre qu\u2019\u00e0 cette \u00e9poque, ce type de fait divers est monnaie courante. Ce qui m\u2019a int\u00e9ress\u00e9e avec Olfa est qu\u2019il s\u2019agit d\u2019une histoire de femmes, de m\u00e8re, de fil<strong>les. <\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color\"><strong>Vous pensiez en faire une fiction ?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-purple-color has-text-color\"><br>\u2014 Je suis pass\u00e9e par diff\u00e9rentes \u00e9tapes. Dans un premier temps, je me suis d\u2019abord dit que j\u2019allais la filmer avec les deux filles qui lui restent pour exprimer l\u2019absence des deux autres. J\u2019ai commenc\u00e9 \u00e0 les filmer en 2016 puis encore en 2017 , mais quelque chose ne marchait pas. Comment raviver les souvenirs sans les embellir, les transformer, sans se donner le beau r\u00f4le, sans \u00e9dulcorer la v\u00e9rit\u00e9? Comment r\u00e9ussir \u00e0 convoquer ce qui a eu lieu et qui n\u2019est plus l\u00e0? Comment affronter la v\u00e9rit\u00e9 de son propre pass\u00e9 des an\u0002n\u00e9es apr\u00e8s? Mais le plus probl\u00e9matique selon moi, c\u2019est la fa\u00e7on dont Olfa jouait un r\u00f4le. \u00c0 partir du moment o\u00f9 j\u2019avais allum\u00e9 ma cam\u00e9ra, elle s\u2019est mise \u00e0 jouer un r\u00f4le en parti\u0002culier. J\u2019ai d\u00fb arr\u00eater le tournage car j\u2019ai fini par comprendre que j\u2019allais tomber dans le pi\u00e8ge qu\u2019elle me tendait<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-purple-color has-text-color\"><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-text-color\"><strong>Quel r\u00f4le jouait-elle et quelle \u00e9tait la nature de ce pi\u00e8ge ?<\/strong><\/p>\n\n\n\n<p class=\"has-vivid-purple-color has-text-color\"><br>\u2014 J\u2019ai remarqu\u00e9 qu\u2019on se comporte souvent dans la vie en \u00e9tant influenc\u00e9 par des clich\u00e9s vus \u00e0 la t\u00e9l\u00e9 ou dans les m\u00e9dias. Olfa avait \u00e9t\u00e9 format\u00e9e par les journalistes. Elle jouait &#8211; avec un grand talent de trag\u00e9dienne &#8211; le r\u00f4le de la m\u00e8re \u00e9plor\u00e9e, hyst\u00e9rique, accabl\u00e9e de culpabilit\u00e9. La plu\u0002part de ces reportages n\u2019autorise pas \u00e0 explorer les dif\u0002f\u00e9rentes dimensions d\u2019un individu. Or Olfa est tellement exub\u00e9rante, tellement ambigu\u00eb, tellement complexe qu\u2019il est impossible de n\u2019en pr\u00e9senter qu\u2019une seule facette. Or, creuser les contradictions, les sensations, les \u00e9motions demande un temps que les journalistes n\u2019ont pas. C\u2019est le r\u00f4le du cin\u00e9ma d\u2019al\u0002ler explorer ces zones-l\u00e0, ces ambigu\u00eft\u00e9s de l\u2019\u00e2me humaine. J\u2019ai commenc\u00e9 alors \u00e0 envisager ce film comme un laboratoire th\u00e9rapeutique de convo\u0002cations de souvenirs.<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color\"><strong>Leur force de r\u00e9silience est ph\u00e9nom\u00e9nale. Quand le film commence, il est surprenant de les voir si radieuses, si souriantes alors qu\u2019on s\u2019attend \u00e0 retrouver des femmes \u00e9plor\u00e9es.<\/strong><\/p>\n\n\n\n<p class=\"has-vivid-purple-color has-text-color\"><br>\u2014 Absolument. Elles sont comme \u00e7a dans la vie. Elles me parlent d\u2019horreur, de trag\u00e9dies et je suis morte de rire. Je<br>voulais montrer ce contraste entre ce qu\u2019on raconte et la fa\u00e7on dont on le raconte. C\u2019est tr\u00e8s pr\u00e9cieux. Le cin\u00e9\u0002ma est capable de montrer \u00e7a. Je crois aussi que le film leur a fait du bien, il leur a servi d\u2019exp\u00e9rience th\u00e9rapeu\u0002tique. Elles ont \u00e9norm\u00e9ment donn\u00e9 et je crois pouvoir dire qu\u2019elles ont re\u00e7u en retour. Elles le disent d\u2019ailleurs. Ce film leur a permis de s\u2019exprimer. Si jusqu\u2019alors elles n\u2019avaient pas de voix, on leur a offert une \u00e9coute. Quand elles ont vu le film, leur premi\u00e8re r\u00e9action a \u00e9t\u00e9 \u00abmerci, tu as port\u00e9 notre voix.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tunisie, (2023), un film de Kaouther Ben Hania. 1h50 avec Hend Sabri, Olfa Hamrouni, Eya Chikahoui Olfa, m\u00e8re de 4 filles, un jour, ses deux filles a\u00een\u00e9es disparaissent. Pour combler &#8230;<\/p>\n","protected":false},"author":1,"featured_media":3175,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-3151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programme-2023-2024"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Les filles d&#039;Olfa&quot; lundi 8 janvier 20h30<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Les filles d&#039;Olfa&quot; lundi 8 janvier 20h30\" \/>\n<meta property=\"og:description\" content=\"Tunisie, (2023), un film de Kaouther Ben Hania. 1h50 avec Hend Sabri, Olfa Hamrouni, Eya Chikahoui Olfa, m\u00e8re de 4 filles, un jour, ses deux filles a\u00een\u00e9es disparaissent. Pour combler ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/\" \/>\n<meta property=\"og:site_name\" content=\"CCB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cin%c3%a9-club-de-B%c3%a9darieux-107423303938487\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-29T13:24:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T09:21:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa-affiche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cineclubbedarieux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cineclubbedarieux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/\"},\"author\":{\"name\":\"cineclubbedarieux\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#\\\/schema\\\/person\\\/f881352cb23c1a4938521c5ec75603d5\"},\"headline\":\"\u00ab\u00a0Les filles d&rsquo;Olfa\u00a0\u00bb lundi 8 janvier 20h30\",\"datePublished\":\"2023-11-29T13:24:24+00:00\",\"dateModified\":\"2025-08-25T09:21:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/\"},\"wordCount\":1207,\"publisher\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/les-filles-dolfa-affiche.jpg\",\"articleSection\":[\"PROGRAMME 2023-2024\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/\",\"url\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/\",\"name\":\"\\\"Les filles d'Olfa\\\" lundi 8 janvier 20h30\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/les-filles-dolfa-affiche.jpg\",\"datePublished\":\"2023-11-29T13:24:24+00:00\",\"dateModified\":\"2025-08-25T09:21:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/les-filles-dolfa-affiche.jpg\",\"contentUrl\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/les-filles-dolfa-affiche.jpg\",\"width\":800,\"height\":418},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/index.php\\\/2023\\\/11\\\/29\\\/les-filles-dolfa-lundi-8-janvier-20h30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Les filles d&rsquo;Olfa\u00a0\u00bb lundi 8 janvier 20h30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#website\",\"url\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/\",\"name\":\"CCB\",\"description\":\"acceuil\",\"publisher\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#organization\",\"name\":\"Cin\u00e9-club de B\u00e9darieux\",\"url\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Cin\u00e9-club de B\u00e9darieux\"},\"image\":{\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cin\u00e9-club-de-B\u00e9darieux-107423303938487\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cineclubbedarieux.fr\\\/#\\\/schema\\\/person\\\/f881352cb23c1a4938521c5ec75603d5\",\"name\":\"cineclubbedarieux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e65d45ec8e98c1171075bbcd0850322bd1cd217b7fea453fa3da6208a47a73f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e65d45ec8e98c1171075bbcd0850322bd1cd217b7fea453fa3da6208a47a73f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e65d45ec8e98c1171075bbcd0850322bd1cd217b7fea453fa3da6208a47a73f5?s=96&d=mm&r=g\",\"caption\":\"cineclubbedarieux\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Les filles d'Olfa\" lundi 8 janvier 20h30","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Les filles d'Olfa\" lundi 8 janvier 20h30","og_description":"Tunisie, (2023), un film de Kaouther Ben Hania. 1h50 avec Hend Sabri, Olfa Hamrouni, Eya Chikahoui Olfa, m\u00e8re de 4 filles, un jour, ses deux filles a\u00een\u00e9es disparaissent. Pour combler ...","og_url":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/","og_site_name":"CCB","article_publisher":"https:\/\/www.facebook.com\/Cin%c3%a9-club-de-B%c3%a9darieux-107423303938487","article_published_time":"2023-11-29T13:24:24+00:00","article_modified_time":"2025-08-25T09:21:54+00:00","og_image":[{"width":800,"height":418,"url":"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa-affiche.jpg","type":"image\/jpeg"}],"author":"cineclubbedarieux","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cineclubbedarieux","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/#article","isPartOf":{"@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/"},"author":{"name":"cineclubbedarieux","@id":"https:\/\/cineclubbedarieux.fr\/#\/schema\/person\/f881352cb23c1a4938521c5ec75603d5"},"headline":"\u00ab\u00a0Les filles d&rsquo;Olfa\u00a0\u00bb lundi 8 janvier 20h30","datePublished":"2023-11-29T13:24:24+00:00","dateModified":"2025-08-25T09:21:54+00:00","mainEntityOfPage":{"@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/"},"wordCount":1207,"publisher":{"@id":"https:\/\/cineclubbedarieux.fr\/#organization"},"image":{"@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/#primaryimage"},"thumbnailUrl":"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa-affiche.jpg","articleSection":["PROGRAMME 2023-2024"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/","url":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/","name":"\"Les filles d'Olfa\" lundi 8 janvier 20h30","isPartOf":{"@id":"https:\/\/cineclubbedarieux.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/#primaryimage"},"image":{"@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/#primaryimage"},"thumbnailUrl":"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa-affiche.jpg","datePublished":"2023-11-29T13:24:24+00:00","dateModified":"2025-08-25T09:21:54+00:00","breadcrumb":{"@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/#primaryimage","url":"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa-affiche.jpg","contentUrl":"https:\/\/cineclubbedarieux.fr\/wp-content\/uploads\/2023\/11\/les-filles-dolfa-affiche.jpg","width":800,"height":418},{"@type":"BreadcrumbList","@id":"https:\/\/cineclubbedarieux.fr\/index.php\/2023\/11\/29\/les-filles-dolfa-lundi-8-janvier-20h30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cineclubbedarieux.fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Les filles d&rsquo;Olfa\u00a0\u00bb lundi 8 janvier 20h30"}]},{"@type":"WebSite","@id":"https:\/\/cineclubbedarieux.fr\/#website","url":"https:\/\/cineclubbedarieux.fr\/","name":"CCB","description":"acceuil","publisher":{"@id":"https:\/\/cineclubbedarieux.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cineclubbedarieux.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cineclubbedarieux.fr\/#organization","name":"Cin\u00e9-club de B\u00e9darieux","url":"https:\/\/cineclubbedarieux.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cineclubbedarieux.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Cin\u00e9-club de B\u00e9darieux"},"image":{"@id":"https:\/\/cineclubbedarieux.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cin\u00e9-club-de-B\u00e9darieux-107423303938487"]},{"@type":"Person","@id":"https:\/\/cineclubbedarieux.fr\/#\/schema\/person\/f881352cb23c1a4938521c5ec75603d5","name":"cineclubbedarieux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e65d45ec8e98c1171075bbcd0850322bd1cd217b7fea453fa3da6208a47a73f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e65d45ec8e98c1171075bbcd0850322bd1cd217b7fea453fa3da6208a47a73f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e65d45ec8e98c1171075bbcd0850322bd1cd217b7fea453fa3da6208a47a73f5?s=96&d=mm&r=g","caption":"cineclubbedarieux"}}]}},"_links":{"self":[{"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/posts\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":8,"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"predecessor-version":[{"id":4445,"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/posts\/3151\/revisions\/4445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/media\/3175"}],"wp:attachment":[{"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cineclubbedarieux.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}